{"id":9277,"date":"2022-11-09T14:33:43","date_gmt":"2022-11-09T13:33:43","guid":{"rendered":"https:\/\/twentytu.com\/datenschutzrichtlinie\/"},"modified":"2025-07-02T15:52:15","modified_gmt":"2025-07-02T14:52:15","slug":"datenschutzrichtlinie","status":"publish","type":"page","link":"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/","title":{"rendered":"Datenschutzrichtlinie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9277\" class=\"elementor elementor-9277 elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6741595b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6741595b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-559c3b\" data-id=\"559c3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1718e1bc elementor-widget elementor-widget-text-editor\" data-id=\"1718e1bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Pol\u00edtica de Privacidad<\/h1>\n<p>\u00a0<\/p>\n<h2>INFORMACI\u00d3N ADICIONAL SOBRE PROTECCI\u00d3N DE DATOS<\/h2>\n<p>Lo que se hace y no se hace con tus datos personales en esta web lo encontrar\u00e1s aqu\u00ed.<\/p>\n<p>Esta pol\u00edtica expresa c\u00f3mo se tratar\u00e1 y proteger\u00e1 la informaci\u00f3n personal de todas las personas que se relacionan con TwentyTu Hi-tech Hostel a trav\u00e9s de este sitio web. Por favor, debes leer todos los apartados del <a href=\"https:\/\/twentytu.com\/de\/rechtliche-warnung\/\">Aviso Legal<\/a>, de la <a href=\"https:\/\/twentytu.com\/de\/cookie-richtlinie\/\">pol\u00edtica de cookies<\/a> y de la presente pol\u00edtica de privacidad antes de utilizar esta web.<\/p>\n<p>De conformidad con lo dispuesto en Reglamento UE 2016\/679, del Parlamento Europeo y del Consejo del 27 de abril de 2016 (RGPD) y la Ley Org\u00e1nica 3\/2018, del 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales, INNOVAT HOTELS SL, te informa de que, mediante la aceptaci\u00f3n de esta Pol\u00edtica de Privacidad, prestas tu consentimiento expreso, informado, libre e inequ\u00edvoco para que los Datos que proporcionas, y sobre los que se aplican las medidas de seguridad, t\u00e9cnicas y organizativas previstas en la normativa vigente, sean tratados por INNOVAT HOTELS SL, como responsable del tratamiento.<\/p>\n<h2>\u00bfQUI\u00c9N ES EL RESPONSABLE DE ESTA WEB?<\/h2>\n<ul>\n<li><strong>Identidad del Responsable:\u00a0<\/strong>INNOVAT HOTELS SL<\/li>\n<li><strong>Nombre comercial:\u00a0<\/strong>TwentyTu Hi-tech Hostel<\/li>\n<li><strong>NIF\/CIF:\u00a0<\/strong>B65237539<\/li>\n<li><strong>Direcci\u00f3n:\u00a0<\/strong>Calle Corsega, 301 &#8211; PLT 3 . DESPACHO 4 08008 Barcelona Espa\u00f1a<\/li>\n<li><strong>Correo electr\u00f3nico:\u00a0<\/strong>reservas@twentytu.com<\/li>\n<li><strong>Actividad:\u00a0<\/strong><\/li>\n<li><strong>Datos de contacto del responsable o representante, y del delegado de protecci\u00f3n de datos<\/strong> en su caso: reservas@twentytu.com<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-669bca0a elementor-widget elementor-widget-text-editor\" data-id=\"669bca0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfQU\u00c9 DATOS PERSONALES SE RECOGEN EN ESTA WEB?<\/h2>\n<p>Para las finalidades establecidas en esta Pol\u00edtica de Privacidad, TwentyTu Hi-tech Hostel\u00a0recaba y trata los Datos Personales que se detallan a continuaci\u00f3n, que depender\u00e1n de los diferentes productos o servicios que solicite en esta Web:<\/p>\n<ul>\n<li><strong>Datos identificativos:<\/strong> nombre, apellidos.<\/li>\n<li><strong>Datos de contacto<\/strong>: direcci\u00f3n postal, correo electr\u00f3nico, n\u00famero de tel\u00e9fono m\u00f3vil.<\/li>\n<li><strong>Datos contractuales:<\/strong> datos de operaciones contractuales, DNI, productos y servicios adquiridos, operaciones financieras, datos de pago.<\/li>\n<li><strong>Datos navegaci\u00f3n<\/strong>: direcci\u00f3n IP, tipo e identificaci\u00f3n del dispositivo, tipo de navegador, dominio a trav\u00e9s del cual accede al Sitio Web, datos de navegaci\u00f3n, actividad en el Sitio Web.<\/li>\n<\/ul>\n<h2>\u00bfCON QU\u00c9 BASE LEGAL SE TRATAN ESOS DATOS?<\/h2>\n<p>Tratamos tus datos personales con las siguientes bases legales:<\/p>\n<ul>\n<li><strong>La\u00a0ejecuci\u00f3n de un contrato\u00a0con <\/strong>TwentyTu Hi-tech Hostel<strong>, <\/strong>para la contrataci\u00f3n de servicios, publicar anuncios y gestionar los servicios solicitados.<\/li>\n<li><strong style=\"font-size: 16px;\">El\u00a0consentimiento<\/strong><span style=\"font-size: 16px;\"> del usuario en relaci\u00f3n al contacto, la suscripci\u00f3n a contenidos y el env\u00edo de comunicaciones comerciales, v\u00eda mail, cookies o sistemas de mensajer\u00eda.<\/span><\/li>\n<\/ul>\n<ul>\n<li><strong>El\u00a0inter\u00e9s leg\u00edtimo<\/strong> del responsable del tratamiento\u00a0para proteger a los usuarios de la web de TwentyTu Hi-tech Hostel\u00a0de abusos y fraudes en el uso de nuestros servicios.<\/li>\n<\/ul>\n<h2>\u00bfCON QU\u00c9 FINALIDADES TRATAREMOS TUS DATOS?<\/h2>\n<p>En esta web, existe diferentes formularios, en cada uno de ellos, la informaci\u00f3n que recoja se utilizar\u00e1 de la siguiente manera:<\/p>\n<ul>\n<li><strong>Formularios de suscripci\u00f3n a contenidos: <\/strong>existen varios formularios para activar la suscripci\u00f3n. Los datos facilitados ser\u00e1n utilizados exclusivamente para enviar la Newsletter y mantenerte actualizado sobre novedades y ofertas puntuales, exclusivas para suscriptores de\u00a0<\/li>\n<li><strong>Formulario de comentarios<\/strong>: Los datos personales introducidos en el formulario para insertar estos comentarios ser\u00e1n utilizados exclusivamente para moderarlos y publicarlos.<\/li>\n<li><strong>Formulario de contacto:<\/strong> Tambi\u00e9n existe un formulario de contacto para consultas, sugerencias o contacto profesional. En este caso se utilizar\u00e1 la direcci\u00f3n de correo electr\u00f3nico para responder a las mismas y enviar la informaci\u00f3n que el usuario requiera a trav\u00e9s de la web.<\/li>\n<li><strong>Formulario de Registro:<\/strong> En este caso, solicitamos los siguientes datos personales: Nombre, Email, para que puedas crear una cuenta en nuestro sistema y dar acceso a sus funcionalidades.<\/li>\n<li><strong>Formulario de venta<\/strong>: Tambi\u00e9n trato datos para gestionar la compra de , incluyendo la gesti\u00f3n del pedido, el pago y todas las operaciones relacionadas con la contrataci\u00f3n del servicio o producto elegido. Esto incluye enviar correos electr\u00f3nicos de seguimiento, respuestas, facturas, recibos, etc.<\/li>\n<li><strong>Formulario alto afiliados<\/strong>: Solicitamos datos de afiliados, incluyendo datos de pago para gestionar el alta de afiliados y liquidar las correspondientes comisiones.<\/li>\n<li><strong>Sistemas de Descargas:<\/strong> En esta web se pueden descargar diferentes contenidos que se incorporan peri\u00f3dicamente en formato <em>texto, video y audio<\/em>. En este caso, se requiere un correo electr\u00f3nico para activar el formulario de suscripci\u00f3n. Se utiliza su informaci\u00f3n con los fines indicados para suscriptores.<\/li>\n<\/ul>\n<h2>TIEMPO DE CONSERVACI\u00d3N DE LOS DATOS PERSONALES<\/h2>\n<p><strong>Datos de los Clientes:<\/strong> El periodo de conservaci\u00f3n de los datos personales variar\u00e1 en funci\u00f3n del servicio que el Cliente contrate. En cualquier caso, ser\u00e1 el m\u00ednimo necesario, pudiendo mantenerse hasta:<\/p>\n<ul>\n<li>4 a\u00f1os: Ley sobre Infracciones y Sanciones en el Orden Social (obligaciones en materia de afiliaci\u00f3n, altas, bajas, cotizaci\u00f3n, pago de salarios\u2026); Arts. 66 y ss. Ley General Tributaria (libros de contabilidad\u2026).<\/li>\n<li>5 a\u00f1os: Art. 1964 del C\u00f3digo Civil (acciones personales sin plazo especial).<\/li>\n<li>6 a\u00f1os: Art. 30 del C\u00f3digo de Comercio (libros de contabilidad, facturas\u2026).<\/li>\n<li>10 a\u00f1os: Art. 25 de la Ley de Prevenci\u00f3n del Blanqueo de Capitales y Financiaci\u00f3n del Terrorismo.<\/li>\n<li><strong>Datos de los suscriptores<\/strong>: Desde que el usuario se suscribe hasta que se da de baja.<\/li>\n<li><strong>Datos de potenciales clientes<\/strong>: los datos se conservar\u00e1n en todo caso durante la vigencia de la relaci\u00f3n comercial establecida y, una vez concluida, dos a\u00f1os, a menos que el usuario solicite antes su supresi\u00f3n.<\/li>\n<\/ul>\n<h2>\u00bfCU\u00c1LES SON TUS DERECHOS EN LO QUE CONCIERNE AL USO DE TUS DATOS?<\/h2>\n<p>Cualquier persona tiene derecho a obtener confirmaci\u00f3n sobre si en TwentyTu Hi-tech Hostel estamos tratando datos personales que le conciernen o no.<\/p>\n<p>Las personas interesadas tienen derecho a:<\/p>\n<ul>\n<li>Solicitar el acceso a los datos personales relativos al interesado.<\/li>\n<li>Solicitar su rectificaci\u00f3n o supresi\u00f3n.<\/li>\n<li>Solicitar su cancelaci\u00f3n.<\/li>\n<li>Solicitar la limitaci\u00f3n de su tratamiento.<\/li>\n<li>Oponerse al tratamiento.<\/li>\n<li>Solicitar la portabilidad de los datos.<\/li>\n<\/ul>\n<p>Si ha otorgado su consentimiento para alguna finalidad concreta, tiene derecho a retirar el consentimiento otorgado en cualquier momento, sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada.<\/p>\n<p>En caso de que sienta vulnerados sus derechos en lo concerniente a la protecci\u00f3n de sus datos personales, especialmente cuando no haya obtenido satisfacci\u00f3n en el ejercicio de sus derechos, puede presentar una reclamaci\u00f3n ante la Autoridad de Control en materia de Protecci\u00f3n de Datos competente a trav\u00e9s de su sitio web: <a href=\"https:\/\/www.aepd.es\/es\"><em>https:\/\/www.aepd.es\/es<\/em><\/a><\/p>\n<p>Para ejercitar estos derechos, puede escribir a\u00a0<span style=\"color: var( --e-global-color-primary );\">reservas@twentytu.com.<\/span><\/p>\n<p><strong>Existe un formulario para el ejercicio de sus derechos<\/strong>, lo puede pedir por email o si lo prefiere, puede usar <a href=\"https:\/\/www.aepd.es\/es\/derechos-y-deberes\/conoce-tus-derechos\"><em>los elaborados por la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos o terceros.<\/em><\/a><\/p>\n<p>Estos formularios deben ir firmados electr\u00f3nicamente o ser acompa\u00f1ados de fotocopia del DNI.<\/p>\n<p>Si le representa alguien, debe adjuntar copia de su DNI, o debe estar firmado con su firma electr\u00f3nica.<\/p>\n<p>Los formularios pueden ser presentados presencialmente, enviados por carta o por mail a la direcci\u00f3n del responsable que aparece al inicio de este texto.<\/p>\n<h2>ACCIONES DE REMARKETING: GOOGLE ADS<\/h2>\n<p>Ads es una plataforma de Google destinada a los ANUNCIANTES que quieren publicitarse en GOOGLE. En https:\/\/twentytu.com\/\u00a0se utiliza Google Ads, la plataforma de publicidad de Google que permite crear campa\u00f1as y anuncios para mostrarlos en otras p\u00e1ginas webs. Al generar un anuncio, se puede segmentar el p\u00fablico por:<\/p>\n<ul>\n<li>Lugar<\/li>\n<li>Datos demogr\u00e1ficos (edad, sexo, etc.)<\/li>\n<li>Intereses (actividades, aficiones, etc.)<\/li>\n<li>Lo que compran en internet y por otros canales<\/li>\n<\/ul>\n<p>Los datos obtenidos a trav\u00e9s de Google Ads est\u00e1n sujetos a esta pol\u00edtica de privacidad desde el momento en que el usuario deja sus datos en el formulario de esta web para unirse al bolet\u00edn de suscripciones. En ning\u00fan caso se utilizar\u00e1 la informaci\u00f3n procedente de Google con una finalidad diferente.<\/p>\n<h2>FACEBOOK ADS<\/h2>\n<p>En esta web se utiliza Facebook Ads:<\/p>\n<p>Facebook Ads permite segmentar el p\u00fablico para dirigir un anuncio.<\/p>\n<p>Gracias a la funci\u00f3n de audiencias personalizadas de Facebook, se puede crear una audiencia a partir de datos de usuarios y suscriptores de esta web, como direcciones de correo electr\u00f3nico y n\u00fameros de tel\u00e9fono. Para ello, es necesario compartir las bases de datos con Facebook para, posteriormente, crear p\u00fablicos personalizados dirigiendo los anuncios a las personas con perfiles similares.<\/p>\n<p>Para la segmentaci\u00f3n de los anuncios de acuerdo con las Pol\u00edticas de Facebook <strong>no se utiliza informaci\u00f3n personal confidencial<\/strong> y no se comparte con terceros ni con otros anunciantes, y ser\u00e1n eliminados por Facebook en cuanto finalice dicho proceso. Adem\u00e1s, Facebook se encargar\u00e1 de asegurar la confidencialidad.<\/p>\n<p>El sistema de anuncios dise\u00f1ado por Facebook permite mostrar anuncios relevantes y <strong>\u00fatiles sin revelar tu identidad a los anunciantes,<\/strong> pudiendo llegar a grupos de personas con perfiles determinados.<\/p>\n<p>En cualquier momento como usuario, puedes revocar tu consentimiento a trav\u00e9s de <a href=\"https:\/\/www.facebook.com\/settings?tab=ads\"><em>https:\/\/www.facebook.com\/settings?tab=ads<\/em><\/a>, donde puedes configurar la recepci\u00f3n de anuncios. Asimismo, puedes indicar que no quieres anuncios basado en intereses de Facebook, ni de otras empresas, a trav\u00e9s de la Alianza Europea de Publicidad Digital Interactiva (EuropeanInteractive Digital Advertising Alliance, EDAA) de YourOn Line Choices (<a href=\"http:\/\/www.youronlinechoices.com\/es\/\"><em>http:\/\/www.youronlinechoices.com\/es\/<\/em><\/a>) o en la configuraci\u00f3n de tu ordenador o tu dispositivo m\u00f3vil.<\/p>\n<p>Para usar la funci\u00f3n de p\u00fablicos personalizados, esta web utiliza la herramienta WebsiteCustomAudience de Facebook, que hace uso del pixel de Facebook que marca al visitante de esta p\u00e1gina web de forma anonimizada. Si deseas oponerte al uso de WebsiteCustomAudiences de Facebook, tienes la posibilidad de hacerlo en: <a href=\"https:\/\/www.facebook.com\/ads\/website_custom_audiences\/\"><em>https:\/\/www.facebook.com\/ads\/website_custom_audiences\/<\/em><\/a>.<\/p>\n<p>Para una mayor informaci\u00f3n sobre el alcance y finalidad de la recogida de los datos por parte de Facebook y su posterior tratamiento, as\u00ed como, para configurar tu privacidad debes acudir a los siguientes enlaces:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/privacy\/explanation\"><em>https:\/\/www.facebook.com\/privacy\/explanation<\/em><\/a>.<\/p>\n<p><strong>Pixel de seguimiento de conversiones de Facebook<\/strong><\/p>\n<p>Para la optimizaci\u00f3n de las campa\u00f1as publicitarias de los anuncios que se publican en Facebook, y con finalidades estad\u00edsticas, se usa el pixel de seguimiento de conversiones de Facebook Inc., 1601 s. California Ave, Palo Alto, CA 94304, que rastrea las acciones de los usuarios despu\u00e9s de hacer clic en un anuncio.<\/p>\n<p>Los datos que se obtienen a trav\u00e9s de dicho pixel son an\u00f3nimos y no hacen referencia a personas f\u00edsicas identificadas, ni se almacenan, ni se crean perfiles con sus datos personales.<\/p>\n<p>Estos datos pueden ser almacenados y tratados por Facebook, y este puede vincular estos datos con tu cuenta de Facebook y tambi\u00e9n utilizarlos para fines publicitarios propios de acuerdo con la pol\u00edtica de uso de datos de Facebook que encontrar\u00e1s en <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\"><em>https:\/\/www.facebook.com\/about\/privacy\/<\/em><\/a>, recientemente actualizada en <a href=\"https:\/\/www.facebook.com\/about\/privacy\/update\"><em>https:\/\/www.facebook.com\/about\/privacy\/update<\/em><\/a>.<\/p>\n<p>Puedes posibilitar a Facebook y a sus socios la inserci\u00f3n de anuncios publicitarios dentro y fuera de Facebook, y para estos fines puede almacenarse una cookie en tu ordenador.<\/p>\n<h2>TWITTER ADS<\/h2>\n<p>En https:\/\/twentytu.com\/\u00a0utilizamos Twitter Ads, la plataforma de publicidad de Twitter, que nos permite crear campa\u00f1as y anuncios. Al generar un anuncio, se puede segmentar el p\u00fablico por:<\/p>\n<ul>\n<li>Lugar<\/li>\n<li>Datos demogr\u00e1ficos (edad, sexo, etc.)<\/li>\n<li>Intereses (actividades, aficiones, etc.)<\/li>\n<li>Lo que compran en internet y por otros canales<\/li>\n<\/ul>\n<p>Los datos obtenidos a trav\u00e9s de Twitter Ads est\u00e1n sujetos a esta pol\u00edtica de privacidad desde el momento en que el usuario deja sus datos en el formulario de esta web para unirse al bolet\u00edn de suscripciones. En ning\u00fan caso se utilizar\u00e1 la informaci\u00f3n procedente de Twitter con una finalidad diferente.<\/p>\n<h2>LINKEDIN ADS<\/h2>\n<p>En https:\/\/twentytu.com\/\u00a0utilizamos LinkedIn Ads, la plataforma de publicidad d LinkedIn que nos permite crear campa\u00f1as y anuncios. Al generar un anuncio, se puede segmentar el p\u00fablico por:<\/p>\n<ul>\n<li>Lugar<\/li>\n<li>Datos demogr\u00e1ficos (edad, sexo, etc.)<\/li>\n<li>Intereses (actividades, aficiones, etc.)<\/li>\n<li>Lo que compran en internet y por otros canales<\/li>\n<\/ul>\n<p>Los datos obtenidos a trav\u00e9s de LinkedIn Ads est\u00e1n sujetos a esta pol\u00edtica de privacidad desde el momento en que el usuario deja sus datos en el formulario de esta web para unirse al bolet\u00edn de suscripciones. En ning\u00fan caso se utilizar\u00e1 la informaci\u00f3n procedente de LinkedIn con una finalidad diferente.<\/p>\n<h2>NOTIFICACI\u00d3N Y DECLARACI\u00d3N DE BRECHAS<\/h2>\n<p><strong>Notificaci\u00f3n de seguridad y declaraci\u00f3n de brechas<\/strong><\/p>\n<p>En INNOVAT HOTELS SL\u00a0asumimos medidas de seguridad adecuadas al nivel de riesgo para proteger la informaci\u00f3n personal contra p\u00e9rdida, uso indebido y acceso no autorizado, divulgaci\u00f3n, alteraci\u00f3n y destrucci\u00f3n, teniendo en cuenta los riesgos que conlleva el procesamiento y la naturaleza de la informaci\u00f3n personal; no obstante, si\u00a0<span style=\"color: var( --e-global-color-primary );\">INNOVAT HOTELS SL<\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-primary );\">\u00a0, determina que sus datos de servicios han sido malversados (incluso por un empleado de\u00a0<\/span>INNOVAT HOTELS SL<span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-primary );\">, se han visto expuestos por una brecha de seguridad o adquiridos de forma incorrecta por un tercero,\u00a0<\/span>INNOVAT HOTELS SL<span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-primary );\">\u00a0te informar\u00e1 de inmediato de dicha brecha de seguridad, apropiaci\u00f3n o adquisici\u00f3n indebida.<\/span><\/p>\n<p><strong>\u00bfA QU\u00c9 DESTINATARIOS SE COMUNICAR\u00c1N TUS DATOS?<\/strong><\/p>\n<p>Muchas herramientas utilizadas en esta web para gestionar datos son contratadas por terceros. Para prestar servicios estrictamente necesarios para el desarrollo de la actividad, INNOVAT HOTELS SL\u00a0comparte datos con los siguientes prestadores bajo sus correspondientes condiciones de privacidad:<\/p>\n<p>Proveedores de servicios externos (por ejemplo, servicios de procesamiento de pago, procesamiento de pedidos, an\u00e1lisis, gesti\u00f3n campa\u00f1as de marketing, gesti\u00f3n de sitios web, y distribuci\u00f3n de correo electr\u00f3nico y otros proveedores de servicios similares) a fin de que estos puedan realizar funciones comerciales en nombre de INNOVAT HOTELS SL.<\/p>\n<p>Pueden tener acceso a esta web de forma ocasional la empresa de desarrollo y mantenimiento web, o la de hosting. Las mismas tienen firmado un contrato de prestaci\u00f3n de servicios que les obliga a mantener el mismo nivel de privacidad que se aplica a los tratamientos realizados en esta web.<\/p>\n<p>Cualquier transferencia internacional de datos derivada de la utilizaci\u00f3n de herramientas o proveedores de servicios, estar\u00e1 adherida al convenio PrivacyShield, que garantiza que las empresas de software americano cumplen las pol\u00edticas de protecci\u00f3n de datos europeas en materia de privacidad, secreto y seguridad de los datos.<\/p>\n<p>Concretamente esta web utiliza las siguientes herramientas:<\/p>\n<ul>\n<li>Herramienta de email marketing:<\/li>\n<li>Herramienta de facturaci\u00f3n:<\/li>\n<li>Herramientas de an\u00e1lisis<\/li>\n<li>Herramienta de chat online<\/li>\n<li>Otras: {describir herramientas} (opcional)<\/li>\n<\/ul>\n<h2>SEGMENTACI\u00d3N Y ELABORACI\u00d3N DE PERFILES<\/h2>\n<p>El registro de los datos personales aportados en el momento de suscripci\u00f3n, contacto, interacci\u00f3n con la web y cualquier otro dato facilitado durante la navegaci\u00f3n, incluyendo la informaci\u00f3n suministrada por las cookies en relaci\u00f3n a los h\u00e1bitos de navegaci\u00f3n, ser\u00e1 utilizada\u00a0\u00a0 a fin de ser segmentados o categorizados con la finalidad de aplicarlos a la actividad relacionada con (la gesti\u00f3n de administraci\u00f3n general, informaci\u00f3n, comercializaci\u00f3n de espacios publicitarios,\u00a0 an\u00e1lisis de propuestas solicitadas por los usuarios\/clientes, estudio estad\u00edstico de los servicios y contenidos utilizados, gustos y preferencias, y encuestas o formularios).<\/p>\n<p>La elaboraci\u00f3n de perfiles, mediante el an\u00e1lisis de tus decisiones individuales automatizadas, consiste en la utilizaci\u00f3n de tus Datos Personales para evaluar determinados aspectos personales, como (el an\u00e1lisis y predicci\u00f3n de su situaci\u00f3n econ\u00f3mica, preferencias personales, intereses, comportamiento, ubicaci\u00f3n, movimientos y actitudes). Siendo la l\u00f3gica aplicada para la obtenci\u00f3n de estos perfiles la utilizaci\u00f3n de procedimientos estad\u00edsticos y siendo las consecuencias de este tratamiento de sus datos mediante la realizaci\u00f3n de perfiles, el env\u00edo de comunicaciones personalizadas de su inter\u00e9s con contenidos relacionados con la actividad desarrollada por\u00a0TwentyTu Hi-tech Hostel.<\/p>\n<p>La base legal para el tratamiento de sus datos para los fines indicados y la elaboraci\u00f3n de decisiones individuales automatizadas elaborando perfiles, es el consentimiento otorgado al marcar la casilla anteriormente indicada.<\/p>\n<p>Los datos que utilizamos en la elaboraci\u00f3n de perfiles y que mostramos a los anunciantes<strong> no son datos que permitan identificar a los usuarios,<\/strong> solo se muestra en una gr\u00e1fica el tipo de p\u00fablico que tenemos, su edad, pa\u00eds, g\u00e9nero, etc.<\/p>\n<h2>ENLACES DE AFILIADOS Y PUBLICIDAD<\/h2>\n<p>En esta web se ofrece al Usuario contenidos patrocinados, anuncios y\/o enlaces de afiliados.<\/p>\n<p>Entre los enlaces que te puedes encontrar, existe la posibilidad de informar y de hacer referencia a productos y\/o servicios y\/o infoproductos de terceros. La informaci\u00f3n que aparece en estos enlaces de afiliados o los anuncios insertados es facilitada por los propios anunciantes, por lo que https:\/\/twentytu.com\/\u00a0no se hace responsable en ning\u00fan caso de inexactitudes o errores que pudieran contener los anuncios, ni puede ofrecer garant\u00edas sobre la experiencia, integridad o responsabilidad de los anunciantes, o la calidad de sus productos y\/o servicios, aunque siempre se recomendar\u00e1n aquellos productos o servicios que https:\/\/twentytu.com\/\u00a0y su equipo hayan probado.<\/p>\n<p>Adem\u00e1s, los anuncios permanecer\u00e1n publicados en el portal hasta que sean eliminados o suspendidos por parte del anunciante o de https:\/\/twentytu.com\/, que l\u00f3gicamente no es responsable de que, una vez dados de baja en sus bases de datos, los anuncios contin\u00faen siendo indexados en buscadores ajenos a este portal.<\/p>\n<p>Todo usuario debe comprender que cualquier relaci\u00f3n contractual o extracontractual entre el Usuario y los anunciantes, afiliados o terceras personas contactadas a trav\u00e9s de esta web, se entienden realizados \u00fanica y exclusivamente entre el usuario y el anunciante y\/o tercera persona.\u00a0<span style=\"color: var( --e-global-color-primary );\">https:\/\/twentytu.com\/<\/span><span style=\"font-style: inherit; font-weight: inherit; color: var( --e-global-color-primary );\">\u00a0\u00fanicamente act\u00faa como cauce o medio publicitario y, por tanto, no tiene ning\u00fan tipo de responsabilidad sobre los da\u00f1os o perjuicios de cualquier naturaleza ocasionados con motivo de sus negociaciones, conversaciones y\/o relaciones contractuales o extracontractuales con los anunciantes o terceras personas f\u00edsicas o jur\u00eddicas contactadas a trav\u00e9s de esta web.<\/span><\/p>\n<h2>SECRETO Y SEGURIDAD DE LOS DATOS<\/h2>\n<p><span style=\"color: var( --e-global-color-primary );\">https:\/\/twentytu.com\/<\/span>\u00a0se compromete al uso y tratamiento de los datos personales del usuario, respetando su confidencialidad, de acuerdo con la finalidad de aquellos; as\u00ed como a dar cumplimiento a su obligaci\u00f3n de guardarlos y adaptar todas las medidas para evitar la alteraci\u00f3n, p\u00e9rdida, tratamiento o acceso no autorizado, de conformidad con lo establecido en la normativa vigente de protecci\u00f3n de datos.<\/p>\n<p>(Esta web incluye un certificado SSL. Se trata de un protocolo de seguridad que hace que tus datos viajen de manera \u00edntegra y segura; es decir, la transmisi\u00f3n de los datos entre un servidor y el usuario web, y en retroalimentaci\u00f3n es totalmente cifrada o encriptada.)<\/p>\n<p>{DOMINIO WEB} no puede garantizar la absoluta inexpugnabilidad de la red Internet, ni, por tanto, la violaci\u00f3n de los datos mediante accesos fraudulentos a ellos por parte de terceros.<\/p>\n<p>Con respecto a la confidencialidad del procesamiento, INNOVAT HOTELS SL\u00a0se asegurar\u00e1 de que cualquier persona que est\u00e9 autorizada por INNOVAT HOTELS SL\u00a0para procesar los datos del cliente (incluido su personal, colaboradores y prestadores), estar\u00e1 bajo la obligaci\u00f3n apropiada de confidencialidad (ya sea un deber contractual o legal).<\/p>\n<p>Cuando se presente alg\u00fan incidente de seguridad, al darse cuenta INNOVAT HOTELS SL\u00a0deber\u00e1 notificar al Cliente sin demoras indebidas y deber\u00e1 proporcionar informaci\u00f3n oportuna relacionada con el Incidente de Seguridad tal como se conozca, o cuando el cliente lo solicite razonablemente.<\/p>\n<h2>EXACTITUD Y VERACIDAD DE LOS DATOS<\/h2>\n<p>Como usuario, eres el \u00fanico responsable de la veracidad y correcci\u00f3n de los datos que remitas a https:\/\/twentytu.com\/, exonerando a INNOVAT HOTELS SL\u00a0\u00a0(TwentyTu Hi-tech Hostel), de cualquier responsabilidad al respecto. Los usuarios garantizan y responden, en cualquier caso, de la exactitud, vigencia y autenticidad de los datos personales facilitados, y se comprometen a mantenerlos debidamente actualizados. El usuario acepta proporcionar informaci\u00f3n completa y correcta en el formulario de contacto o suscripci\u00f3n.<\/p>\n<h2>REVOCABILIDAD<\/h2>\n<p>El consentimiento prestado, tanto para el tratamiento como para la cesi\u00f3n de los datos de los interesados, es revocable en cualquier momento comunic\u00e1ndolo a INNOVAT HOTELS SL\u00a0\u00a0(TwentyTu Hi-tech Hostel) en los t\u00e9rminos establecidos en esta Pol\u00edtica para el ejercicio de los derechos ARCO. Esta revocaci\u00f3n en ning\u00fan caso tendr\u00e1 car\u00e1cter retroactivo.<\/p>\n<h2>CAMBIOS EN LA POL\u00cdTICA DE PRIVACIDAD<\/h2>\n<p><span style=\"color: var( --e-global-color-primary );\">INNOVAT HOTELS SL<\/span><span style=\"color: var( --e-global-color-primary );\">\u00a0<\/span>\u00a0se reserva el derecho a modificar la presente pol\u00edtica para adaptarla a novedades legislativas o jurisprudenciales, as\u00ed como a pr\u00e1cticas de la industria. En dichos supuestos, anunciar\u00e1 en esta p\u00e1gina los cambios introducidos con razonable antelaci\u00f3n a su puesta en pr\u00e1ctica.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidad \u00a0 INFORMACI\u00d3N ADICIONAL SOBRE PROTECCI\u00d3N DE DATOS Lo que se hace y no se hace con tus datos personales en esta web lo encontrar\u00e1s aqu\u00ed. Esta pol\u00edtica expresa c\u00f3mo se tratar\u00e1 y proteger\u00e1 la informaci\u00f3n personal de todas las personas que se relacionan con a trav\u00e9s de este sitio web. Por favor, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"tags":[],"class_list":["post-9277","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzrichtlinie | TwentyT\u00fa Hostel<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzrichtlinie | TwentyT\u00fa Hostel\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de Privacidad \u00a0 INFORMACI\u00d3N ADICIONAL SOBRE PROTECCI\u00d3N DE DATOS Lo que se hace y no se hace con tus datos personales en esta web lo encontrar\u00e1s aqu\u00ed. Esta pol\u00edtica expresa c\u00f3mo se tratar\u00e1 y proteger\u00e1 la informaci\u00f3n personal de todas las personas que se relacionan con a trav\u00e9s de este sitio web. Por favor, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/\" \/>\n<meta property=\"og:site_name\" content=\"TwentyT\u00fa Hostel\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T14:52:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"19\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/\",\"url\":\"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/\",\"name\":\"Datenschutzrichtlinie | TwentyT\u00fa Hostel\",\"isPartOf\":{\"@id\":\"https:\/\/twentytu.com\/de\/#website\"},\"datePublished\":\"2022-11-09T13:33:43+00:00\",\"dateModified\":\"2025-07-02T14:52:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/twentytu.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzrichtlinie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/twentytu.com\/de\/#website\",\"url\":\"https:\/\/twentytu.com\/de\/\",\"name\":\"TwentyT\u00fa Hostel\",\"description\":\"Descubre un nuevo concepto de albergue en Barcelona. Albergue eco-sostenible con terraza en la azotea, buenas vistas y Wi-Fi gratis.\",\"publisher\":{\"@id\":\"https:\/\/twentytu.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/twentytu.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/twentytu.com\/de\/#organization\",\"name\":\"TwentyT\u00fa Hostel\",\"url\":\"https:\/\/twentytu.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/twentytu.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/twentytu.com\/wp-content\/uploads\/2024\/03\/logo-twentytu.png\",\"contentUrl\":\"https:\/\/twentytu.com\/wp-content\/uploads\/2024\/03\/logo-twentytu.png\",\"width\":550,\"height\":173,\"caption\":\"TwentyT\u00fa Hostel\"},\"image\":{\"@id\":\"https:\/\/twentytu.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzrichtlinie | TwentyT\u00fa Hostel","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Datenschutzrichtlinie | TwentyT\u00fa Hostel","og_description":"Pol\u00edtica de Privacidad \u00a0 INFORMACI\u00d3N ADICIONAL SOBRE PROTECCI\u00d3N DE DATOS Lo que se hace y no se hace con tus datos personales en esta web lo encontrar\u00e1s aqu\u00ed. Esta pol\u00edtica expresa c\u00f3mo se tratar\u00e1 y proteger\u00e1 la informaci\u00f3n personal de todas las personas que se relacionan con a trav\u00e9s de este sitio web. Por favor, [&hellip;]","og_url":"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/","og_site_name":"TwentyT\u00fa Hostel","article_modified_time":"2025-07-02T14:52:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"19\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/","url":"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/","name":"Datenschutzrichtlinie | TwentyT\u00fa Hostel","isPartOf":{"@id":"https:\/\/twentytu.com\/de\/#website"},"datePublished":"2022-11-09T13:33:43+00:00","dateModified":"2025-07-02T14:52:15+00:00","breadcrumb":{"@id":"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/twentytu.com\/de\/datenschutzrichtlinie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/twentytu.com\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzrichtlinie"}]},{"@type":"WebSite","@id":"https:\/\/twentytu.com\/de\/#website","url":"https:\/\/twentytu.com\/de\/","name":"TwentyT\u00fa Hostel","description":"Descubre un nuevo concepto de albergue en Barcelona. Albergue eco-sostenible con terraza en la azotea, buenas vistas y Wi-Fi gratis.","publisher":{"@id":"https:\/\/twentytu.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/twentytu.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/twentytu.com\/de\/#organization","name":"TwentyT\u00fa Hostel","url":"https:\/\/twentytu.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/twentytu.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/twentytu.com\/wp-content\/uploads\/2024\/03\/logo-twentytu.png","contentUrl":"https:\/\/twentytu.com\/wp-content\/uploads\/2024\/03\/logo-twentytu.png","width":550,"height":173,"caption":"TwentyT\u00fa Hostel"},"image":{"@id":"https:\/\/twentytu.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/pages\/9277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/comments?post=9277"}],"version-history":[{"count":1,"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/pages\/9277\/revisions"}],"predecessor-version":[{"id":9278,"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/pages\/9277\/revisions\/9278"}],"wp:attachment":[{"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/media?parent=9277"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twentytu.com\/de\/wp-json\/wp\/v2\/tags?post=9277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}